{"id":8335,"date":"2017-10-09T08:55:54","date_gmt":"2017-10-09T07:55:54","guid":{"rendered":"https:\/\/www.4webs.es\/blog\/?p=8335"},"modified":"2017-10-06T11:00:46","modified_gmt":"2017-10-06T10:00:46","slug":"navegacion-facetas-prestashop-1-7","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7","title":{"rendered":"Navegaci\u00f3n por facetas en Prestashop 1.7"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p>Hace ya tiempo que los administradores y due\u00f1os de <a href=\"https:\/\/www.4webs.es\/tienda-prestashop\">tiendas online cuentan con Prestashop<\/a> 1.7, una de las versiones m\u00e1s nuevas y vigentes de este software especializado en e-commerce. Nuevos dise\u00f1os, back office simplificado y facilidades para trabajar con el SEO, han sido las grandes apuestas de la presente versi\u00f3n. No obstante, una de las herramientas que m\u00e1s destacan de este programa es el <strong>bloque de navegaci\u00f3n por facetas<\/strong>. Esta herramienta ya hab\u00eda sido incorporada en pasadas presentaciones, pero su actualizaci\u00f3n ha dado bastante de qu\u00e9 hablar. Para quienes a\u00fan no sepan de qu\u00e9 se trata esta opci\u00f3n, a continuaci\u00f3n, veremos de qu\u00e9 se trata y cu\u00e1les son las posibilidades que ofrece a partir de Prestashop 1.7.<\/p>\n<h2>\u00bfQu\u00e9 es la navegaci\u00f3n por facetas?<\/h2>\n<p>La forma tradicional de navegar por una tienda online para buscar los productos es mediante la <a href=\"https:\/\/www.4webs.es\/tienda\/es\/modulos-prestashop-16\/158-categorias-selectivas.html\">exploraci\u00f3n de categor\u00edas<\/a>. Tras elegir una clasificaci\u00f3n primaria de productos, se pasa a seleccionar el objeto, posteriormente su precio, modalidad, color, etc. El resultado: muchos usuarios desist\u00edan, porque deb\u00edan revisar muchas p\u00e1ginas y ofertas hasta poder dar con el objeto deseado.<\/p>\n<p>Por eso, Prestashop cre\u00f3 un innovador sistema bajo el cual los compradores seleccionan de antemano todas las caracter\u00edsticas que desean de su objeto buscado. La navegaci\u00f3n se hace mucho m\u00e1s sencilla e intuitiva, pudiendo centrarse el cliente en otros aspectos estrat\u00e9gicos de la compra como el precio, la distancia o la reputaci\u00f3n del vendedor. Gracias a este instrumento, la exploraci\u00f3n puede entenderse como una posibilidad de buscar otras alternativas con mayor libertad.<\/p>\n<figure id=\"attachment_8360\" aria-describedby=\"caption-attachment-8360\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8360 size-full\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-en-prestashop-1.7.jpg\" alt=\"\" width=\"750\" height=\"763\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-en-prestashop-1.7.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-en-prestashop-1.7-295x300.jpg 295w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-en-prestashop-1.7-413x420.jpg 413w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-8360\" class=\"wp-caption-text\">Ejemplo de los filtros en una tienda online ficticia<\/figcaption><\/figure>\n<h3>Personalizando el m\u00f3dulo de categor\u00edas<\/h3>\n<p>Prestashop 1.7 no solo te permite crear este m\u00f3dulo con categor\u00edas para la b\u00fasqueda. Adem\u00e1s, con este software <strong>puedes personalizar una herramienta que en la mayor\u00eda de las tiendas digitales se ubica en el sidebar de las p\u00e1ginas<\/strong> en donde aparecen las categor\u00edas. Los desarrolladores ahora pueden modificar los c\u00f3digos para enganchar dicho modulo en cualquier otra parte de la plantilla de la p\u00e1gina web. El potencial de esta alternativa est\u00e1 en que ahora podemos revolucionar el estilo tradicional de las tiendas online e intentar hacer mucho m\u00e1s intuitiva la navegaci\u00f3n del usuario. Con estas opciones, hablamos de personalizaci\u00f3n del m\u00f3dulo de categor\u00edas. Y, adem\u00e1s, esto nos posibilita la creaci\u00f3n de nuevos formatos y estilos innovadores.<\/p>\n<h3>Definiendo los filtros<\/h3>\n<p>Una de las claves est\u00e1 en establecer internamente la composici\u00f3n de los <a href=\"https:\/\/www.4webs.es\/blog\/tipos-filtros-avanzados-una-tienda-ecommerce\">filtros que contribuir\u00e1n a facilitar la b\u00fasqueda del cliente<\/a>. La idea es que nosotros configuremos los controles que tenemos a mano, seg\u00fan la categor\u00eda que creamos adecuada. Es as\u00ed como podremos crear plantillas de filtrados, para lo cual se deben definir dos aspectos trascendentales. <strong>Primero, las categor\u00edas<\/strong>, que al ser seleccionadas activar\u00e1n a las plantillas de filtros. <strong>En segundo lugar, los filtros<\/strong> concretos que tendr\u00e1 el modulo para cada categor\u00eda seg\u00fan los tipos de producto. Hay que recordar que no se pueden usar las mismas categor\u00edas para aparatos electr\u00f3nicos, que por ejemplo para una prenda de vestir. Quienes tienen tiendas donde se venden m\u00faltiples productos entienden esta realidad.<\/p>\n<h3>Filtros y tipos de controles<\/h3>\n<p>Las opciones de filtros que tenemos para configurar las plantillas son varias. Algunas ideas b\u00e1sicas son las siguientes: Subcategor\u00eda, stock, peso, color, precio, fabricantes, atributos del producto, modelo, etc. La idea es que, si algunas de esas opciones no se muestran, <strong>el cliente sepa que no podr\u00e1 conseguir de antemano una oferta con dicha caracter\u00edstica<\/strong>.<\/p>\n<figure id=\"attachment_8345\" aria-describedby=\"caption-attachment-8345\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8345\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/seleccion-de-filtros-prestashop-1.7.jpg\" alt=\"\" width=\"750\" height=\"562\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/seleccion-de-filtros-prestashop-1.7.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/seleccion-de-filtros-prestashop-1.7-300x225.jpg 300w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/seleccion-de-filtros-prestashop-1.7-560x420.jpg 560w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-8345\" class=\"wp-caption-text\">Selecci\u00f3n de filtros en la versi\u00f3n 1.7<\/figcaption><\/figure>\n<p>A\u00f1adido a esto, el modulo nos permite definir la forma en que cada filtro se ve en la pantalla y si podemos elegir unos controles u otros. Esto es central en la usabilidad de la p\u00e1gina y la navegaci\u00f3n de los visitantes. Es as\u00ed como a la hora de filtrar, los compradores podr\u00e1n elegir entre varias opciones, tener una opci\u00f3n entre varias o incluso, ver una lista desplegable de alternativas para realizar su b\u00fasqueda.<\/p>\n<h4>Recomendaciones finales<\/h4>\n<p>Es aconsejable no agrupar anuncios en categor\u00edas en las cuales no exista una buena cantidad de productos. En estos casos, lo mejor es que la navegaci\u00f3n sea directa y as\u00ed evitamos que el usuario crea err\u00f3neamente que no existe variedad en nuestra tienda. Este es un riesgo innecesario. Quiz\u00e1s una limitaci\u00f3n con la cual se encontrar\u00e1n los desarrolladores m\u00e1s avanzados, es la dificultad para modificar el modulo con respecto a su funcionalidad. Con todo esto, esta herramienta tiene todo lo necesario para facilitar las b\u00fasquedas, personalizar el cajet\u00edn y colocarlo en donde m\u00e1s nos agrade. Sin duda, una herramienta del cual adolecen otras plataformas.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones<\/p>\n","protected":false},"author":5,"featured_media":8342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"class_list":{"0":"post-8335","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prestashop"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Navegaci\u00f3n por facetas en Prestashop 1.7 | 4webs.es<\/title>\n<meta name=\"description\" content=\"El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Navegaci\u00f3n por facetas en Prestashop 1.7 | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-09T07:55:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-prestashop-1.7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n 4webs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n 4webs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7\"},\"author\":{\"name\":\"Redacci\u00f3n 4webs\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\"},\"headline\":\"Navegaci\u00f3n por facetas en Prestashop 1.7\",\"datePublished\":\"2017-10-09T07:55:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7\"},\"wordCount\":844,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/navegacion-por-facetas-prestashop-1.7.jpg\",\"articleSection\":[\"Prestashop\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7\",\"name\":\"Navegaci\u00f3n por facetas en Prestashop 1.7 | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/navegacion-por-facetas-prestashop-1.7.jpg\",\"datePublished\":\"2017-10-09T07:55:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\"},\"description\":\"El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/navegacion-por-facetas-prestashop-1.7.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/navegacion-por-facetas-prestashop-1.7.jpg\",\"width\":840,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/navegacion-facetas-prestashop-1-7#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Navegaci\u00f3n por facetas en Prestashop 1.7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\",\"name\":\"Redacci\u00f3n 4webs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n 4webs\"},\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/redaccion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Navegaci\u00f3n por facetas en Prestashop 1.7 | 4webs.es","description":"El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7","og_locale":"es_ES","og_type":"article","og_title":"Navegaci\u00f3n por facetas en Prestashop 1.7 | 4webs.es","og_description":"El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones","og_url":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2017-10-09T07:55:54+00:00","og_image":[{"width":840,"height":440,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-prestashop-1.7.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n 4webs","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Redacci\u00f3n 4webs","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7"},"author":{"name":"Redacci\u00f3n 4webs","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6"},"headline":"Navegaci\u00f3n por facetas en Prestashop 1.7","datePublished":"2017-10-09T07:55:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7"},"wordCount":844,"commentCount":2,"image":{"@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-prestashop-1.7.jpg","articleSection":["Prestashop"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7","url":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7","name":"Navegaci\u00f3n por facetas en Prestashop 1.7 | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-prestashop-1.7.jpg","datePublished":"2017-10-09T07:55:54+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6"},"description":"El m\u00f3dulo de navegaci\u00f3n por facetas o filtros es muy \u00fatil sobre todo en los casos donde la tienda online tiene muchos productos con bastantes combinaciones","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-prestashop-1.7.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/10\/navegacion-por-facetas-prestashop-1.7.jpg","width":840,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/navegacion-facetas-prestashop-1-7#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"Navegaci\u00f3n por facetas en Prestashop 1.7"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6","name":"Redacci\u00f3n 4webs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","caption":"Redacci\u00f3n 4webs"},"url":"https:\/\/www.4webs.es\/blog\/author\/redaccion"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/8335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=8335"}],"version-history":[{"count":8,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/8335\/revisions"}],"predecessor-version":[{"id":8359,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/8335\/revisions\/8359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/8342"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=8335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=8335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=8335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}