{"id":8243,"date":"2019-09-20T08:19:39","date_gmt":"2019-09-20T07:19:39","guid":{"rendered":"https:\/\/www.4webs.es\/blog\/?p=8243"},"modified":"2020-09-07T12:08:00","modified_gmt":"2020-09-07T11:08:00","slug":"tecnica-del-knolling-fotografia-producto","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto","title":{"rendered":"T\u00e9cnica del knolling para fotograf\u00eda de producto"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p>Se le llama knolling a una t\u00e9cnica que consiste en <a href=\"https:\/\/www.4webs.es\/blog\/equipo-para-realizar-fotografia-y-video-de-producto\">fotografiar objetos<\/a>, que han sido <strong>previamente organizados con base en un concepto<\/strong>. En este sentido podr\u00eda compararse con los bodegones, es decir, una composici\u00f3n elaborada para mostrar un conjunto de objetos que guardan una relaci\u00f3n entre s\u00ed. Al knolling tambi\u00e9n se le ha definido como una <strong>t\u00e9cnica para hacer bodegones cenitales<\/strong>. Esto se debe a que las fotograf\u00edas casi siempre se capturan desde un \u00e1ngulo de \u201cpicado\u201d, es decir, de arriba hacia abajo.<\/p>\n<p>Una definici\u00f3n estrictamente t\u00e9cnica podr\u00eda ser la siguiente: proceso de organizar objetos que guardan una relaci\u00f3n entre s\u00ed, los cuales se disponen en l\u00edneas paralelas o \u00e1ngulos de 90\u00b0, con el fin de transmitir un mensaje conceptual o est\u00e9tico. La mayor\u00eda de las fotos con esta t\u00e9cnica incluyen <strong>objetos que tienen un patr\u00f3n com\u00fan<\/strong>, bien sea de forma, color, concepto o tema. Sin embargo, tambi\u00e9n es frecuente que incluyan otros elementos complementarios o adicionales.<\/p>\n<h2>Los or\u00edgenes del knolling<\/h2>\n<p>Este tipo de t\u00e9cnica no es nueva. En realidad, fue creada en 1989 en el estudio del arquitecto Frank Gehry. Este canadiense se dedicaba a dise\u00f1ar muebles, objetos y edificios. Su estudio era un verdadero desastre, pues ten\u00eda objetos y papeles desperdigados por todas partes. En una ocasi\u00f3n estaba creando una colecci\u00f3n de sillas para la compa\u00f1\u00eda Knoll. Era tal el desorden, que a su empleado Andrew Kromelow se le ocurri\u00f3 organizar las piezas en el suelo para poder ensamblar las sillas de una forma m\u00e1s eficaz.<\/p>\n<p>De este modo, tom\u00f3 todas las piezas y las herramientas y las orden\u00f3 paralelamente. Quer\u00eda saber d\u00f3nde estaba cada cosa, de una sola mirada. As\u00ed naci\u00f3 la m\u00e1xima del knolling: se debe <strong>ubicar en el espacio solo aquello que sea imprescindible<\/strong>, el resto sobra. Con el tiempo, se descubri\u00f3 que esta forma de organizar los objetos daba como resultado unas im\u00e1genes muy bellas que merec\u00edan fotografiarse. El concepto lleg\u00f3 primero al arte y luego a la publicidad. Esta \u00faltima la llev\u00f3 a las redes sociales y logr\u00f3 que se convirtiera en tendencia.<\/p>\n<h2>Los principios de esta t\u00e9cnica<\/h2>\n<p>El objetivo de este tipo de fotograf\u00edas es conformar una colecci\u00f3n de objetos para contar una historia o trasmitir un concepto de estilo. Se trata de una tendencia minimalista. Esto quiere decir que se basa en la supresi\u00f3n de elementos innecesarios, bajo el principio de que \u201cmenos es m\u00e1s\u201d. En principio, esta t\u00e9cnica era sobre todo un sistema de organizaci\u00f3n. Se le ha comparado con el m\u00e9todo japon\u00e9s de organizaci\u00f3n llamado \u201clas 5 s\u201d, que incluye los siguientes atributos:<\/p>\n<ul>\n<li>Seiri, clasificaci\u00f3n<\/li>\n<li>Seiton, orden<\/li>\n<li>Seiso, limpieza<\/li>\n<li>Seiketsu, estandarizaci\u00f3n<\/li>\n<li>Shitsuke, disciplina<\/li>\n<\/ul>\n<p>Estos principios se aplicaron inicialmente a las gu\u00edas de montaje de artefactos o a los gr\u00e1ficos t\u00e9cnicos. Sin embargo, en la actualidad este procedimiento ha ido rompiendo las barreras de lo utilitario y adquiriendo una dimensi\u00f3n m\u00e1s compleja, que incluye objetivos comunicativos y est\u00e9ticos por ejemplo para <a href=\"https:\/\/www.4webs.es\/blog\/fotografia-de-producto-en-tu-tienda-online\">fotografiar productos para tiendas online<\/a>.<\/p>\n<h3>La gu\u00eda de Tom Sachs<\/h3>\n<p>Tom Sachs es uno de los artistas que ha incorporado los principios del knolling a su producci\u00f3n de esculturas. En su libro Ten Bullets enunci\u00f3 un procedimiento para \u201cknollear\u201d, que se puede sintetizar en cuatro pasos:<\/p>\n<ul>\n<li>Explorar el entorno en busca de objetos que no se est\u00e9n utilizando.<\/li>\n<li>Guardar todo lo que no se use.<\/li>\n<li>Agrupar los objetos que tengan alguna similitud entre s\u00ed.<\/li>\n<li>Alinear los objetos elegidos o disponerlos en \u00e1ngulo recto sobre una superficie.<\/li>\n<li>Lo que sigue es fotografiar desde un \u00e1ngulo panor\u00e1mico. Una vez cumplidos todos esos pasos, actualmente lo siguiente es publicar la fotograf\u00eda en las redes sociales, particularmente en Pinterest o Instagram.<\/li>\n<\/ul>\n<figure id=\"attachment_8273\" aria-describedby=\"caption-attachment-8273\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8273\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/how-to-knoll-by-tom-sachs.jpg\" alt=\"\" width=\"750\" height=\"493\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/how-to-knoll-by-tom-sachs.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/how-to-knoll-by-tom-sachs-300x197.jpg 300w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/how-to-knoll-by-tom-sachs-639x420.jpg 639w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-8273\" class=\"wp-caption-text\">C\u00f3mo realizar el Knolling por Tom Sachs<\/figcaption><\/figure>\n<h4>Aplicaciones<\/h4>\n<p>Actualmente se aplica a todo tipo de objetos. Desde elementos de ferreter\u00eda hasta delicias gastron\u00f3micas. Sin embargo, el campo en el que ha logrado un mayor nivel de aceptaci\u00f3n y difusi\u00f3n es en el sector de moda y belleza. La t\u00e9cnica knolling se presta mucho para dise\u00f1ar \u201coutfits\u201d o atuendos completos. Permiten armar un look particular, con gran estilo. En las im\u00e1genes aparecen todos los elementos que, combinados entre s\u00ed, dan lugar a un atuendo bello y con personalidad. Es usual que en las mismas fotograf\u00edas aparezcan los accesorios o complementos que le dan el toque final a todo.<\/p>\n<p>Este tipo de fotograf\u00edas han demostrado ser un aut\u00e9ntico multiplicador de las ventas, en especial en la modalidad online. Tienen la ventaja de que contribuyen a afianzar la imagen de marca, debido principalmente a que generan im\u00e1genes de f\u00e1cil recuerdo, dentro de los usuarios de redes sociales. As\u00ed mismo, tienen un enorme potencial para la <a href=\"https:\/\/www.4webs.es\/blog\/las-ventas-cruzadas-en-comercio-electronico\">venta cruzada<\/a> o cross-selling e influyen en la compra de productos adicionales (como accesorios o complementos, en el caso de la moda). Todo depende de los elementos que se incorporen a la composici\u00f3n.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.<\/p>\n","protected":false},"author":5,"featured_media":8271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-8243","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marketing-online","8":"has-post-video"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9cnica del knolling para fotograf\u00eda de producto | 4webs.es<\/title>\n<meta name=\"description\" content=\"Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9cnica del knolling para fotograf\u00eda de producto | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-20T07:19:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-07T11:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/tecnica-del-knolling-para-fotografiar-productos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n 4webs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n 4webs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto\"},\"author\":{\"name\":\"Redacci\u00f3n 4webs\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\"},\"headline\":\"T\u00e9cnica del knolling para fotograf\u00eda de producto\",\"datePublished\":\"2019-09-20T07:19:39+00:00\",\"dateModified\":\"2020-09-07T11:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto\"},\"wordCount\":874,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/tecnica-del-knolling-para-fotografiar-productos.jpg\",\"articleSection\":[\"Marketing online\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto\",\"name\":\"T\u00e9cnica del knolling para fotograf\u00eda de producto | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/tecnica-del-knolling-para-fotografiar-productos.jpg\",\"datePublished\":\"2019-09-20T07:19:39+00:00\",\"dateModified\":\"2020-09-07T11:08:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\"},\"description\":\"Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/tecnica-del-knolling-para-fotografiar-productos.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/tecnica-del-knolling-para-fotografiar-productos.jpg\",\"width\":840,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/tecnica-del-knolling-fotografia-producto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9cnica del knolling para fotograf\u00eda de producto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\",\"name\":\"Redacci\u00f3n 4webs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n 4webs\"},\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/redaccion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9cnica del knolling para fotograf\u00eda de producto | 4webs.es","description":"Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9cnica del knolling para fotograf\u00eda de producto | 4webs.es","og_description":"Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.","og_url":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2019-09-20T07:19:39+00:00","article_modified_time":"2020-09-07T11:08:00+00:00","og_image":[{"width":840,"height":440,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/tecnica-del-knolling-para-fotografiar-productos.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n 4webs","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Redacci\u00f3n 4webs","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto"},"author":{"name":"Redacci\u00f3n 4webs","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6"},"headline":"T\u00e9cnica del knolling para fotograf\u00eda de producto","datePublished":"2019-09-20T07:19:39+00:00","dateModified":"2020-09-07T11:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto"},"wordCount":874,"commentCount":0,"image":{"@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/tecnica-del-knolling-para-fotografiar-productos.jpg","articleSection":["Marketing online"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto","url":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto","name":"T\u00e9cnica del knolling para fotograf\u00eda de producto | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/tecnica-del-knolling-para-fotografiar-productos.jpg","datePublished":"2019-09-20T07:19:39+00:00","dateModified":"2020-09-07T11:08:00+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6"},"description":"Este tipo de t\u00e9cnica creativa sirve para fotografiar objetos que comparten un mismo estilo, concepto, forma, color o tem\u00e1tica, se usa tambi\u00e9n en ecommerce.","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/tecnica-del-knolling-para-fotografiar-productos.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/09\/tecnica-del-knolling-para-fotografiar-productos.jpg","width":840,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/tecnica-del-knolling-fotografia-producto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"T\u00e9cnica del knolling para fotograf\u00eda de producto"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6","name":"Redacci\u00f3n 4webs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","caption":"Redacci\u00f3n 4webs"},"url":"https:\/\/www.4webs.es\/blog\/author\/redaccion"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/8243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=8243"}],"version-history":[{"count":8,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/8243\/revisions"}],"predecessor-version":[{"id":8278,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/8243\/revisions\/8278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/8271"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=8243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=8243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=8243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}