{"id":696,"date":"2011-01-29T14:41:26","date_gmt":"2011-01-29T12:41:26","guid":{"rendered":"http:\/\/www.4webs.es\/blog\/?p=696"},"modified":"2020-09-28T11:21:40","modified_gmt":"2020-09-28T10:21:40","slug":"modulo-facebook-para-prestashop","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop","title":{"rendered":"M\u00f3dulo Facebook para Prestashop"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p style=\"text-align: center;\"><a href=\"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop\/facebook_comment\" rel=\"attachment wp-att-1115\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1115\"  src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg\" alt=\"\" width=\"551\" height=\"248\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg 551w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment-300x135.jpg 300w\" sizes=\"auto, (max-width: 551px) 85vw, 551px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><strong>ACTUALIZADO JULIO 2011<\/strong><\/p>\n<p>Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra <a  href=\"https:\/\/www.4webs.es\/tiendas-virtuales.php\">tienda online<\/a>, y conseguir aumentar las ventas, ya que como sabr\u00e9is las redes sociales cuentan con mucho reconocimiento por parte de los buscadores, por lo que toda mejora enfocada hac\u00eda las redes nos permitir\u00e1 aumentar las visitas.<\/p>\n<p>Hemos desarrollado un m\u00f3dulo para Prestashop 1.4 que lo incluye , son los principales botones de las redes sociales\u00a0 Google+1, Twitter y Facebook (Me gusta y enviar) totalmente administrable.<\/p>\n<p>El m\u00f3dulo lo usaremos como un bloque y nos permitir\u00e1 ver quienes son \u00abFANS\u00bb de nuestro grupo, totalmente recomendable.<\/p>\n<p>Descargar<a href=\"http:\/\/www.svmemory.com\/blockfanpage.rar\"> M\u00d3DULO PRETASHOP FACEBOOK<\/a><\/p>\n<p>Actualizo la informaci\u00f3n acerca de este m\u00f3dulo para Prestashop e incluyo uno nuevo en dondo el usuario puede agregar a la pesta\u00f1a del producto \u00abme gusta\u00bb\u00a0 y la cantidad de gente que le gusta ese producto.<\/p>\n<p>A\u00f1adimos otro nuevo m\u00f3dulo cuya funci\u00f3n es similar el primero con la diferencia que este monta un men\u00fa flotante lateral, d\u00e1ndoles un aspecto muy web 2.0 y que dejar\u00e1 el <a  href=\"https:\/\/www.4webs.es\/\">dise\u00f1o web<\/a> muy actual.<\/p>\n<p>Descargar m\u00f3dulo Facebook Slide<\/p>\n<p>Otro nuevo m\u00f3dulo de facebook que permite publicar comentarios directamente en la p\u00e1gina<\/p>\n<p>Descargar m\u00f3dulo comentarios facebook<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y conseguir aumentar las ventas, ya que como sabr\u00e9is las redes sociales cuentan con mucho reconocimiento por parte de los buscadores, por lo que toda mejora enfocada hac\u00eda las redes &hellip; <a href=\"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abM\u00f3dulo Facebook para Prestashop\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"class_list":{"0":"post-696","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prestashop"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f3dulo Facebook para Prestashop | 4webs.es<\/title>\n<meta name=\"description\" content=\"ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f3dulo Facebook para Prestashop | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-29T12:41:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-28T10:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"248\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Risue\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Risue\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop\"},\"author\":{\"name\":\"Pablo Risue\u00f1o\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"headline\":\"M\u00f3dulo Facebook para Prestashop\",\"datePublished\":\"2011-01-29T12:41:26+00:00\",\"dateModified\":\"2020-09-28T10:21:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop\"},\"wordCount\":222,\"commentCount\":28,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/facebook_comment.jpg\",\"articleSection\":[\"Prestashop\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop\",\"name\":\"M\u00f3dulo Facebook para Prestashop | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/facebook_comment.jpg\",\"datePublished\":\"2011-01-29T12:41:26+00:00\",\"dateModified\":\"2020-09-28T10:21:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"description\":\"ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/facebook_comment.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/facebook_comment.jpg\",\"width\":551,\"height\":248},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-facebook-para-prestashop#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00f3dulo Facebook para Prestashop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\",\"name\":\"Pablo Risue\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"caption\":\"Pablo Risue\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/www.4webs.es\"],\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00f3dulo Facebook para Prestashop | 4webs.es","description":"ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop","og_locale":"es_ES","og_type":"article","og_title":"M\u00f3dulo Facebook para Prestashop | 4webs.es","og_description":"ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y","og_url":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2011-01-29T12:41:26+00:00","article_modified_time":"2020-09-28T10:21:40+00:00","og_image":[{"width":551,"height":248,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg","type":"image\/jpeg"}],"author":"Pablo Risue\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Pablo Risue\u00f1o","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop"},"author":{"name":"Pablo Risue\u00f1o","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"headline":"M\u00f3dulo Facebook para Prestashop","datePublished":"2011-01-29T12:41:26+00:00","dateModified":"2020-09-28T10:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop"},"wordCount":222,"commentCount":28,"image":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg","articleSection":["Prestashop"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop","url":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop","name":"M\u00f3dulo Facebook para Prestashop | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg","datePublished":"2011-01-29T12:41:26+00:00","dateModified":"2020-09-28T10:21:40+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"description":"ACTUALIZADO JULIO 2011 Y hoy por partida doble os dejo otro m\u00f3dulo de muchisima utilidad ya que con \u00e9l podremos posicionar mejor nuestra tienda online, y","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2010\/05\/facebook_comment.jpg","width":551,"height":248},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/modulo-facebook-para-prestashop#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"M\u00f3dulo Facebook para Prestashop"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048","name":"Pablo Risue\u00f1o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","caption":"Pablo Risue\u00f1o"},"sameAs":["http:\/\/www.4webs.es"],"url":"https:\/\/www.4webs.es\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":24,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/696\/revisions"}],"predecessor-version":[{"id":11969,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/696\/revisions\/11969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/1115"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}