{"id":6652,"date":"2020-03-15T08:26:37","date_gmt":"2020-03-15T07:26:37","guid":{"rendered":"https:\/\/www.4webs.es\/blog\/?p=6652"},"modified":"2020-09-07T14:58:00","modified_gmt":"2020-09-07T13:58:00","slug":"puedes-mejorar-posicionamiento-seo-local-google-my-business","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business","title":{"rendered":"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p>Estar posicionados en los resultados locales (<strong>SEO Local<\/strong>) es de vital importancia para la mayor\u00eda de los negocios f\u00edsicos, ya sean oficinas de empresas o tiendas.<\/p>\n<p>Y m\u00e1s a\u00fan cuando tras los <a href=\"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\">cambios realizados por Google en su algoritmo<\/a>, ahora solo podemos visualizar 3 resultados y que adem\u00e1s los introduce por encima del resto de resultados habituales.<\/p>\n<p>Es decir, lo primero que ver\u00e1 el usuario al introducir una b\u00fasqueda como por ejemplo \u201c<a href=\"https:\/\/www.4webs.es\/diseno-tiendas-online\"><strong>dise\u00f1o tiendas online<\/strong><\/a>\u201d, son los 3 resultados posicionados en <strong>Google Maps:<\/strong><\/p>\n<figure id=\"attachment_6656\" aria-describedby=\"caption-attachment-6656\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6656\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/seo-local-google-maps-4webs.jpg\" alt=\"\" width=\"750\" height=\"867\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/seo-local-google-maps-4webs.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/seo-local-google-maps-4webs-260x300.jpg 260w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/seo-local-google-maps-4webs-363x420.jpg 363w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-6656\" class=\"wp-caption-text\">Ejemplo de nuestra posici\u00f3n en Google Maps por el t\u00e9rmino \u00abdise\u00f1o tiendas online\u00bb<\/figcaption><\/figure>\n<h2>Darnos de alta en Google\u00a0My Business<\/h2>\n<p>Antes que nada, tienes que dar de alta tu negocio en <strong>Google My Business<\/strong>. Para ello, inicia sesi\u00f3n con tu cuenta de Google (parece obvio decir que es mejor si te das de alta con la cuenta de la empresa que con la personal, pero m\u00e1s vale prevenir&#8230;)<\/p>\n<p>Eso s\u00ed, luego podr\u00e1s dar acceso a tu cuenta personal para realizar los cambios oportunos y realizar los pertinentes seguimientos.<\/p>\n<figure id=\"attachment_6654\" aria-describedby=\"caption-attachment-6654\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6654 size-full\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/google-my-business.jpg\" alt=\"\" width=\"750\" height=\"247\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/google-my-business.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/google-my-business-300x99.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-6654\" class=\"wp-caption-text\">Apartado de Google My Business<\/figcaption><\/figure>\n<p>Cuando hacemos clic en el bot\u00f3n de \u00abobtener tu p\u00e1gina\u00bb, aparecer\u00e1 una pantalla con tres opciones para elegir tu tipo de tienda:<\/p>\n<ul>\n<li><strong>Escaparate:<\/strong> Puede ser un restaurante, una tienda minorista o un hotel entre otros.<\/li>\n<li><strong>\u00c1rea de servicio:<\/strong> Fontaneros, taxis o servicios a domicilio por ejemplo.<\/li>\n<li><strong>Marca:<\/strong> Vendes productos, equipos deportivos, eres un grupo musical, etc.<\/li>\n<\/ul>\n<p>NOTA: Si tienes varias tiendas puedes utilizar la opci\u00f3n de varias localizaciones: \u00abDirecciones de Google My Business\u00bb<\/p>\n<figure id=\"attachment_6659\" aria-describedby=\"caption-attachment-6659\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6659 size-full\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/elige-tipo-de-tienda-google-my-business.jpg\" alt=\"\" width=\"750\" height=\"343\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/elige-tipo-de-tienda-google-my-business.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/elige-tipo-de-tienda-google-my-business-300x137.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-6659\" class=\"wp-caption-text\">Debes elegir tu tipo de tienda entre \u00abEscaparate\u00bb, \u00ab\u00c1rea de servicio\u00bb o \u00abMarca\u00bb en Google My Business<\/figcaption><\/figure>\n<p>Despu\u00e9s de elegir cualquiera de esas opciones anteriores, te debe aparecer un mapa para comprobar que tu negocio ya est\u00e1 o no y as\u00ed poder o bien rellenar los datos desde cero o modificarlos en el caso de que tu negocio ya estuviese activo en Google.<\/p>\n<p>Cuando termines de rellenarlos, vas a tener que verificar tu p\u00e1gina a trav\u00e9s de un c\u00f3digo que te enviar\u00e1n a la direcci\u00f3n que hayas introducido.<\/p>\n<p>Llegados hasta este punto, la p\u00e1gina de tu negocio ya est\u00e1 en Google My Business, simple, \u00bfverdad?<\/p>\n<p>Esta p\u00e1gina tambi\u00e9n te va a servir como p\u00e1gina de Google Plus y con la que tu negocio aparecer\u00e1 en Google Maps.<\/p>\n<h2>Rellenar tu perfil de negocio en Google My Business<\/h2>\n<p>A partir de este punto, empieza lo bueno. Ahora es cuando el trabajo de optimizaci\u00f3n de tu p\u00e1gina Google My Business debe ser constante y lo m\u00e1s importante, tener siempre los datos lo m\u00e1s actualizados y reales posibles.<\/p>\n<figure id=\"attachment_6662\" aria-describedby=\"caption-attachment-6662\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6662\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/google-my-business-4webs.jpg\" alt=\"\" width=\"750\" height=\"225\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/google-my-business-4webs.jpg 750w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/google-my-business-4webs-300x90.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-6662\" class=\"wp-caption-text\">Ejemplo del perfil de 4webs en Google My Business<\/figcaption><\/figure>\n<p>Una vez que accedes a la pantalla de edici\u00f3n (mediante el bot\u00f3n de \u00abEditar\u00bb), deber\u00edas de completar y tener en cuenta los siguientes <strong>factores para optar a posicionarte entre los primeros puestos en Google Maps.<\/strong><\/p>\n<h2>\u00bfQu\u00e9 ayuda a posicionarnos mejor en SEO local?<\/h2>\n<ul>\n<li>Rellena todos los campos (nombre, categor\u00eda de negocio, informaci\u00f3n de contacto, descripci\u00f3n de tu negocio&#8230;) y <strong>trata de mantener actualizado\u00a0tu perfil<\/strong> con toda aquella\u00a0informaci\u00f3n que pueda ser relevante para tus clientes.<\/li>\n<li>A\u00f1ade la <strong>localidad de tu negocio<\/strong> y si puedes, un\u00a0<strong>GEO Sitemap<\/strong>\u00a0y un\u00a0<strong>archivo KML\u00a0a Google Earth.<\/strong><\/li>\n<li>No menosprecies la importancia de las\u00a0<strong>categor\u00edas secundarias<\/strong> que abarquen toda tu oferta, para ello, puedes realizar por ejemplo un <a href=\"https:\/\/www.semrush.com\/?ref=2017035779\">estudio de palabras clave con la herramienta SEMrush<\/a>. (Y ojo, a\u00f1adir esas palabras clave relevantes tanto en el contenido de la descripci\u00f3n de tu empresa como en el contenido multimedia que subas)<\/li>\n<li>A\u00f1ade <strong>contenido multimedia<\/strong>\u00a0que aporte valor a tu empresa ya que Google que subas fotos y videos que puedan aportar cercan\u00eda y calidez a los usuarios.<\/li>\n<li><strong>Google+<\/strong> es el ni\u00f1o predilecto de Google as\u00ed que si no todav\u00eda no tienes perfil en esta red social, ya est\u00e1s tardando y por supuesto, mantenla actualizada.<\/li>\n<li>Y si localizas a un fot\u00f3grafo de confianza\u00a0de Google que\u00a0a\u00f1ada una visita 360\u00ba de\u00a0tu negocio, much\u00edsimo mejor.<\/li>\n<li>Ni qu\u00e9 decir tiene que debes tener tu <strong>sitio web optimizado para SEO<\/strong>.<\/li>\n<li>Lo ideal es que consigas\u00a0<strong>rese\u00f1as de tus clientes<\/strong>. \u00a0Pero, \u00a1mucho cuidado! estas rese\u00f1as deben ser 100% ver\u00eddicas ya que Google no es tonto y si te penaliza ya puedes despedirte de una buena posici\u00f3n en las SERPs locales por mucho tiempo.<\/li>\n<li>Eso s\u00ed, responde a todas y cada una de las rese\u00f1as que recibas, cuida a tus clientes.<\/li>\n<li>No te olvides de <strong>estudiar a tu competencia<\/strong> y ver qu\u00e9 est\u00e1n haciendo mal para t\u00fa hacerlo mejor.<\/li>\n<\/ul>\n<h2>Otras ventajas del posicionamiento local<\/h2>\n<p><strong>El branding<\/strong>: Simplemente apareciendo con nuestro nombre comercial, ya hace que el usuario nos perciba como marca. Nos aporta visibilidad y confianza teniendo por tanto m\u00e1s probabilidades de convertir.<\/p>\n<p><strong>Las llamadas a la acci\u00f3n<\/strong>: Gracias a que Google nos facilita el\u00a0acceso directo a nuestro sitio web y\u00a0un bot\u00f3n de llamada directa en el m\u00f3vil, \u00bfno crees que es una estupenda manera para realizar una conversi\u00f3n en solo dos clicks?<\/p>\n<p><strong>La confianza<\/strong>:<strong>\u00a0<\/strong>S\u00e9 transparente en todo momento. Las opiniones de tus clientes actuales favorecer\u00e1n much\u00edsimos a futuros clientes as\u00ed que cu\u00eddalos y ofrece lo mejor de ti.<\/p>\n<p>Si quieres mejorar tu posicionamiento local en Google Maps, \u00bfa qu\u00e9 esperas para darte de alta en\u00a0Google My Business o actualizar tu perfil?<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps<\/p>\n","protected":false},"author":5,"featured_media":6676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-6652","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marketing-online"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business | 4webs.es<\/title>\n<meta name=\"description\" content=\"\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-15T07:26:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-07T13:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/posicionamiento-seo-local-google-maps.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n 4webs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n 4webs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business\"},\"author\":{\"name\":\"Redacci\u00f3n 4webs\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\"},\"headline\":\"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business\",\"datePublished\":\"2020-03-15T07:26:37+00:00\",\"dateModified\":\"2020-09-07T13:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business\"},\"wordCount\":968,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/posicionamiento-seo-local-google-maps.jpg\",\"articleSection\":[\"Marketing online\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business\",\"name\":\"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/posicionamiento-seo-local-google-maps.jpg\",\"datePublished\":\"2020-03-15T07:26:37+00:00\",\"dateModified\":\"2020-09-07T13:58:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\"},\"description\":\"\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/posicionamiento-seo-local-google-maps.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/posicionamiento-seo-local-google-maps.jpg\",\"width\":840,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/puedes-mejorar-posicionamiento-seo-local-google-my-business#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/62f884c014f31a905b25c80c2a62c7f6\",\"name\":\"Redacci\u00f3n 4webs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n 4webs\"},\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/redaccion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business | 4webs.es","description":"\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business | 4webs.es","og_description":"\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps","og_url":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2020-03-15T07:26:37+00:00","article_modified_time":"2020-09-07T13:58:00+00:00","og_image":[{"width":840,"height":440,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/posicionamiento-seo-local-google-maps.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n 4webs","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Redacci\u00f3n 4webs","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business"},"author":{"name":"Redacci\u00f3n 4webs","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6"},"headline":"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business","datePublished":"2020-03-15T07:26:37+00:00","dateModified":"2020-09-07T13:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business"},"wordCount":968,"commentCount":0,"image":{"@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/posicionamiento-seo-local-google-maps.jpg","articleSection":["Marketing online"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business","url":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business","name":"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/posicionamiento-seo-local-google-maps.jpg","datePublished":"2020-03-15T07:26:37+00:00","dateModified":"2020-09-07T13:58:00+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6"},"description":"\u00bfTu negocio tiene perfil en Google My Business? o lo tienes, \u00bfpero no actualizado? Pues te ser\u00e1 m\u00e1s dif\u00edcil que est\u00e9s en la primera posici\u00f3n de Google Maps","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/posicionamiento-seo-local-google-maps.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2017\/03\/posicionamiento-seo-local-google-maps.jpg","width":840,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/puedes-mejorar-posicionamiento-seo-local-google-my-business#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"C\u00f3mo puedes mejorar el posicionamiento SEO Local con Google My Business"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/62f884c014f31a905b25c80c2a62c7f6","name":"Redacci\u00f3n 4webs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2d897afb8cdf95491cff01ee900d40ab01a2ccec9be78b108f5189c837a601a?s=96&d=mm&r=g","caption":"Redacci\u00f3n 4webs"},"url":"https:\/\/www.4webs.es\/blog\/author\/redaccion"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/6652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=6652"}],"version-history":[{"count":22,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/6652\/revisions"}],"predecessor-version":[{"id":6681,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/6652\/revisions\/6681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/6676"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=6652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=6652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=6652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}