{"id":4970,"date":"2016-01-07T07:08:37","date_gmt":"2016-01-07T06:08:37","guid":{"rendered":"http:\/\/www.4webs.es\/blog\/?p=4970"},"modified":"2015-12-23T16:45:15","modified_gmt":"2015-12-23T15:45:15","slug":"nuevo-cambios-en-el-algoritmo-de-busqueda-de-google","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google","title":{"rendered":"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p>Hace pocas semanas Google publicaba una nueva <a href=\"https:\/\/static.googleusercontent.com\/media\/www.google.com\/es\/\/insidesearch\/howsearchworks\/assets\/searchqualityevaluatorguidelines.pdf\">gu\u00eda de evaluaci\u00f3n de un sitio web en PDF<\/a>. Fue en 2013 cuando esta compa\u00f1\u00eda public\u00f3 su primera gu\u00eda.<\/p>\n<p>Su objetivo era:<\/p>\n<blockquote><p>\u201cproporcionar transparencia sobre el funcionamiento de Google y ayudar a los webmasters a entender lo que Google busca en las p\u00e1ginas web\u201d.<\/p><\/blockquote>\n<p>Ya sabemos que Google realiza cambios peri\u00f3dicos en su algoritmo de b\u00fasqueda. Recientemente supimos que las webs que incluyesen un <a href=\"https:\/\/www.4webs.es\/blog\/anuncias-tu-app-en-tu-web-cuidado-google-te-podria-penalizar\">anuncio de instalaci\u00f3n de una app<\/a> ocultando una gran cantidad de contenido ser\u00edan penalizadas. As\u00ed funciona el algoritmo de Google, un elemento fundamental en el posicionamiento web que obliga a los responsables de una p\u00e1gina a estar mirando siempre de reojo a los cambios que propone el gigante de Mountain View.<\/p>\n<p>Para llevar a cabo estos cambios, Google tiene una red de colaboradores denominados evaluadores cuya funci\u00f3n es <strong>\u201cvalorar la calidad de la b\u00fasqueda de Google\u201d<\/strong>. Sus conclusiones ofrecen claves para el buscador a la hora de realizar cambios en su algoritmo.<\/p>\n<h2>Las tiendas online y el algoritmo de Google<\/h2>\n<p>Fue <strong>en 2012<\/strong> cuando se produjo uno de los cambios m\u00e1s dr\u00e1sticos en la pol\u00edtica de posicionamiento web de la firma californiana. Se comenz\u00f3 a penalizar el link building, <strong>una estrategia SEO que basaba la autoridad de una web en la cantidad de enlaces entrantes que recib\u00eda<\/strong>.<\/p>\n<p>Como se suele decir, hecha la ley, hecha la trampa. Los expertos SEO trataban de mejorar el posicionamiento de sus webs multiplicando el n\u00famero de enlaces entrantes a trav\u00e9s del uso de las denominadas granjas de enlaces o con enlaces de baja calidad. Pero lleg\u00f3 la actualizaci\u00f3n <a href=\"https:\/\/www.4webs.es\/blog\/el-seo-es-para-los-que-aceptan-las-reglas\">Google Penguin<\/a> derrib\u00f3, al menos en parte, esta tendencia un tanto sospechosa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5006\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/linkbuilding-seo.png\" alt=\"linkbuilding-seo\" width=\"685\" height=\"394\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/linkbuilding-seo.png 685w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/linkbuilding-seo-300x173.png 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>Te\u00f3ricamente Google siempre trata de mejorar la experiencia del usuario. Y decimos \u201cte\u00f3ricamente\u201d porque el inmenso poder, casi inabarcable, que tiene Google para decidir lo que debe encontrar el usuario en sus b\u00fasquedas, lo que debe leer y lo que no, asusta. Pero esto es otra historia. A efectos pr\u00e1cticos, el propietario de un e-commerce debe respetar las directrices de Google si quiere que su tienda online este bien posicionada y sus contenidos est\u00e9n f\u00e1cilmente accesibles a los usuarios.<\/p>\n<p>Tras el gran cambio que supuso<strong> Google Penguin<\/strong>, los expertos SEO <strong>tuvieron que trabajar en otras estrategias para mejorar el posicionamiento<\/strong>. Con sus sucesivos cambios de algoritmo, Google trata de premiar a las webs que ofrecen contenido de calidad. Por eso, nuestros e-commerce deben siempre estar abiertos a cambios para satisfacer esta \u201cdemanda de calidad\u201d de Google.<\/p>\n<h2>El contenido de una tienda online debe aportar valor al usuario<\/h2>\n<p>Los cambios que se derivan de la <strong>nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016<\/strong> podr\u00edan influir mucho en el posicionamiento de los e-commerce. Una estructura habitual en estas webs es usar un contenido de apoyo debajo de los productos para ayudar a posicionar. Seg\u00fan se extrae de la actualizaci\u00f3n de la gu\u00eda, <strong>estas p\u00e1ginas de categor\u00eda de e-commerce podr\u00edan bajar su posicionamiento a favor de las p\u00e1ginas que ofrezcan contenido relacionado con la intenci\u00f3n de b\u00fasqueda del usuario<\/strong>. Es decir, que el <strong>contenido aporte valor<\/strong>, \u00bfincluso aunque est\u00e9 duplicado? Lo que est\u00e1 claro es que generar contenido por generar ya no funciona, ahora hay que<\/p>\n<p>Ya sabemos que el contenido duplicado es una de las primeras causas de descenso en Google. Parece que la curaci\u00f3n de contenido si es a favor de ofrecer valor al usuario podr\u00eda no ser tan perjudicial para el posicionamiento. As\u00ed mismo, <strong>Google tambi\u00e9n podr\u00eda perjudicar a los sitios web que usan las palabras clave de otras marcas para ayudar a posicionarse<\/strong>.<\/p>\n<p>De cualquier forma, todos estos cambios de Google todav\u00eda deben ser contrastados. Aun es pronto para sacar conclusiones acerca de las consecuencias que se deriva de la publicaci\u00f3n de esta nueva gu\u00eda de evaluaci\u00f3n web de Google.<\/p>\n<p>Para los propietarios de un e-commerce la variaci\u00f3n en el algoritmo, es decir en los criterios de posicionamiento de Google, es trascendental, por ello debemos estar atentos a la evoluci\u00f3n en las pr\u00f3ximas semanas de nuestras tiendas online. Se dice tambi\u00e9n que los cambios <strong>en los resultados de b\u00fasqueda y la clasificaci\u00f3n se producir\u00e1n en tiempo real<\/strong>, lo cual beneficiar\u00eda a los webmasters para adaptar sus estrategias SEO con mayor rapidez.<\/p>\n<p>Pero, como decimos, por el momento lo \u00fanico que nos queda es \u201cvigilar\u201d los cambios de posicionamiento en nuestra webs para comprobar si las novedades de Google tienen una repercusi\u00f3n real en las mismas.<\/p>\n<p>Para ello, no est\u00e1 de m\u00e1s que analicemos con calma la nueva gu\u00eda de evaluaci\u00f3n web, es nuestra recomendaci\u00f3n para este comienzo de a\u00f1o, nosotros ya estamos leyendo toda la gu\u00eda y analizando punto por punto&#8230;y si quer\u00e9is profundizar un poquito m\u00e1s os recomendamos este ar\u00edculo de <a href=\"http:\/\/www.apasionadosdelmarketing.es\/guia-de-google-para-evaluar-la-calidad-de-un-sitio-web\/\">apasionadosdelmarketing<\/a>.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.<\/p>\n","protected":false},"author":1,"featured_media":5001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-4970","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marketing-online"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016 | 4webs.es<\/title>\n<meta name=\"description\" content=\"Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016 | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-07T06:08:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/search-google-quality.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"447\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Risue\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Risue\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\"},\"author\":{\"name\":\"Pablo Risue\u00f1o\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"headline\":\"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016\",\"datePublished\":\"2016-01-07T06:08:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\"},\"wordCount\":856,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/search-google-quality.jpg\",\"articleSection\":[\"Marketing online\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\",\"name\":\"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016 | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/search-google-quality.jpg\",\"datePublished\":\"2016-01-07T06:08:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"description\":\"Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/search-google-quality.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/search-google-quality.jpg\",\"width\":852,\"height\":447},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\",\"name\":\"Pablo Risue\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"caption\":\"Pablo Risue\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/www.4webs.es\"],\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016 | 4webs.es","description":"Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google","og_locale":"es_ES","og_type":"article","og_title":"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016 | 4webs.es","og_description":"Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.","og_url":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2016-01-07T06:08:37+00:00","og_image":[{"width":852,"height":447,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/search-google-quality.jpg","type":"image\/jpeg"}],"author":"Pablo Risue\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Pablo Risue\u00f1o","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google"},"author":{"name":"Pablo Risue\u00f1o","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"headline":"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016","datePublished":"2016-01-07T06:08:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google"},"wordCount":856,"commentCount":1,"image":{"@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/search-google-quality.jpg","articleSection":["Marketing online"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google","url":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google","name":"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016 | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/search-google-quality.jpg","datePublished":"2016-01-07T06:08:37+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"description":"Los cambios que se derivan de la nueva actualizaci\u00f3n de la gu\u00eda de evaluaci\u00f3n web de Google 2016 podr\u00edan influir mucho en el posicionamiento de los e-commerce, desc\u00e1rgate la gu\u00eda en pdf y descubre las novedades.","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/search-google-quality.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2016\/01\/search-google-quality.jpg","width":852,"height":447},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/nuevo-cambios-en-el-algoritmo-de-busqueda-de-google#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"Nuevo cambios en el algoritmo de b\u00fasqueda de Google, 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048","name":"Pablo Risue\u00f1o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","caption":"Pablo Risue\u00f1o"},"sameAs":["http:\/\/www.4webs.es"],"url":"https:\/\/www.4webs.es\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/4970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=4970"}],"version-history":[{"count":9,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/4970\/revisions"}],"predecessor-version":[{"id":5008,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/4970\/revisions\/5008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/5001"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=4970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=4970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=4970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}