{"id":4106,"date":"2019-12-18T07:28:28","date_gmt":"2019-12-18T06:28:28","guid":{"rendered":"http:\/\/www.4webs.es\/blog\/?p=4106"},"modified":"2020-09-07T12:28:25","modified_gmt":"2020-09-07T11:28:25","slug":"comparativa-getresponse-vs-mailchimp","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp","title":{"rendered":"Comparativa Getresponse vs Mailchimp"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p>Tanto <a href=\"http:\/\/www.getresponse.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">GetResponse<\/a> como <a  href=\"http:\/\/mailchimp.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">MailChimp<\/a> son las <strong>dos herramientas<\/strong> del mercado actual del <strong><a  href=\"https:\/\/www.4webs.es\/blog\/newsletter-en-comercio-electronico\" target=\"_blank\" rel=\"noopener noreferrer\">email marketing<\/a> m\u00e1s usadas en el mundo<\/strong>. Ambas son muy \u00fatiles para el usuario y elegir una de ellas no va a ser tarea f\u00e1cil. Para simplificar la tarea y orientar la decisi\u00f3n, vamos a realizar\u00a0una <strong>comparativa entre GetResponse vs MailChimp<\/strong> que explica cu\u00e1les son las ventajas e inconvenientes que presentan, as\u00ed como sus diferencias m\u00e1s significativas.<\/p>\n<h2>Similitudes entre Getresponse y Mailchimp<\/h2>\n<p>Ambas plataformas <strong>permiten importar una base de datos,<\/strong> en este caso una lista de correo, y almacenarla mediante los formularios de registro del sitio web. Posteriormente, esto nos permite poder env\u00edar a los mails de esos suscriptores publicaciones que interesan al suscriptor, es decir, boletines peri\u00f3dicos. Adem\u00e1s, ofrecen la posibilidad de que el usuario de la plataforma pueda tener un <strong>seguimiento detallado del \u00e9xito de su correo<\/strong>, mediante estad\u00edsticas como la <strong>tasa de apertura del correo<\/strong> y de los <strong>clics realizados<\/strong> hacia la p\u00e1gina en cuesti\u00f3n.<\/p>\n<p>Adem\u00e1s es importante usar un sistema de este tipo, ya que somos conocedores que muchas empresas usan el mismo Outlook para hacer este tipo de env\u00edos, esto presenta un problema, y es muchas veces <strong>tenemos limitaciones en el servidor que no nos permiten enviar una cantidad de correos en tan poco tiempo<\/strong>, otra limitaci\u00f3n es como muchas veces los <strong>recibiremos en Spam<\/strong>, tanto Mailchimp como Getresponse tienen acuerdos para superar estas barreras, y nos podr\u00e1 garantizar el \u00e9xito de nuestra campa\u00f1a. Y adem\u00e1s, no ocurrir\u00e1 el t\u00edpico despiste donde\u00a0en ocasiones nos olvidamos de poner en copia oculta a todos los destinatarios.<\/p>\n<p><a href=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/pantallas-get-response.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4115\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/pantallas-get-response.jpg\" alt=\"pantallas-get-response\" width=\"852\" height=\"373\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/pantallas-get-response.jpg 852w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/pantallas-get-response-300x131.jpg 300w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/pantallas-get-response-800x350.jpg 800w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a><\/p>\n<p>En resumen, lo que ambos consiguen es <strong>automatizar el proceso de email marketing<\/strong>. Una ventaja a\u00f1adida es que, adem\u00e1s de enviar boletines y hacer seguimiento, permiten dar respuestas autom\u00e1ticas al suscriptor, felicitarle por su cumplea\u00f1os, ofrecerle descuentos, etc. Es decir, generar una respuesta autom\u00e1tica en base a determinados datos almacenados del suscriptor, o bien, crearnos listas de env\u00edo en funci\u00f3n de las preferencias de nuestros usuarios, si usamos Prestashop, incluso podremos importar f\u00e1cilmente los usuarios a cualquiera de las dos plataformas mediante excels o usar alg\u00fan m\u00f3dulo que sincronice los datos.<\/p>\n<p>Tanto en Mailchimp como Getresponse disponemos de temas b\u00e1sicos para poder dise\u00f1ar plantillas de calidad en poco tiempo, y sobre todo mucho m\u00e1s efectivas que cualquier email que podamos enviar nosotros manualmente.<\/p>\n<h2>Las diferencias entre las plataformas<\/h2>\n<p>Lo primero que debe destacarse es que <strong>GetResponse ofrece precios a simple vista m\u00e1s econ\u00f3micos<\/strong>, aunque el margen sea escaso. Sin embargo, las diferencias de precio son m\u00ednimas y, adem\u00e1s, <strong>MailChimp ofrece m\u00e1s opciones en cuanto a franjas de precios<\/strong>. Esta \u00faltima tiene un <strong>plan gratuito<\/strong> que permite al usuario <strong>enviar hasta 12.000 mensajes a un m\u00e1ximo de 2.000 suscriptores por mes<\/strong>. Otra ventaja de MailChimp es que tiene m\u00e1s plantillas que GetResponse.<\/p>\n<p>Una diferencia significativa es la interface. Mientras MailChimp tiene fuentes m\u00e1s grandes y variadas para mostrar los men\u00fas, estad\u00edsticas y otros datos, as\u00ed como un asistente m\u00e1s funcional mediante lista de tareas pendientes, GetResponse es m\u00e1s tradicional y funciona mediante men\u00fas desplegables.<\/p>\n<p>En cuanto al dise\u00f1o de correos electr\u00f3nicos, los temas, nosotros\u00a0preferimos MailChimp porque es m\u00e1s sencillo y sobre todo mas intuitivo, basta con ir soltando los elementos para que se acoplen al dise\u00f1o. Para la versi\u00f3n de <strong>correos para m\u00f3vil<\/strong>, sin embargo, lleva ventaja <strong>GetResponse<\/strong>, ya que ofrece vista previa en tiempo real que permite ir visualizando los pasos dados y el resultado, en Mailchimp aunque tambi\u00e9n lo incorpora es bastante m\u00e1s lento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4113\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/informes-get-response.jpg\" alt=\"informes-get-response\" width=\"852\" height=\"373\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/informes-get-response.jpg 852w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/informes-get-response-300x131.jpg 300w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/informes-get-response-800x350.jpg 800w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>En los informes, <strong>MailChimp permite calificar a los suscriptores y clasificarlos<\/strong>, facilitando la identificaci\u00f3n de los que son mejores para nosotros, pero Getresponse utiliza gr\u00e1ficos que resultan visualmente m\u00e1s esclarecedores. En cuanto a la integraci\u00f3n de servicios, <strong>GetResponse es m\u00e1s completo y permite integrar m\u00faltiples servicios, como Paypal o Facebook<\/strong>.<\/p>\n<p>GetResponse adem\u00e1s incluye un sistema de Pruebas A\/B para ver que campa\u00f1as, botones, colores, texto o cualquier cosa que se nos pueda ocurrir en el dise\u00f1o del correo para medir cual de los dos es m\u00e1s efectivo.<\/p>\n<p>Un punto que no me gusta nada de <strong>Mailchimp es el borrado de listas y usuarios<\/strong>, se nota que lo han hecho para \u00abjoder\u00bb, para borrar una lista debe pasar una semana sin que la uses, y los usuarios debes borrarlos manualmente uno a uno, vamos una aut\u00e9ntica putada, se nota que cobran por el tama\u00f1o de subscriptores principalmente.<\/p>\n<p>Sin duda, ambos son excelentes mecanismos para optimizar el email marketing. Solo quedar\u00e1 elegir el que se adapte de forma m\u00e1s completa a las necesidades de cada usuario sopesando las ventajas mencionadas de cada herramienta, si que os decimos que nosotros usamos Mailchimp, pero habr\u00e1 que vigilar de cerca\u00a0a Getresponse que se va acercando muy r\u00e1pido a sus competidores a precios m\u00e1s competitivos.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo. Ambas son muy \u00fatiles para el usuario y elegir una de ellas no va a ser tarea f\u00e1cil.<\/p>\n","protected":false},"author":1,"featured_media":4109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":{"0":"post-4106","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marketing-online"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comparativa Getresponse vs Mailchimp | 4webs.es<\/title>\n<meta name=\"description\" content=\"Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comparativa Getresponse vs Mailchimp | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-18T06:28:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-07T11:28:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/mailchimp-getresponse-comparativa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"447\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Risue\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Risue\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp\"},\"author\":{\"name\":\"Pablo Risue\u00f1o\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"headline\":\"Comparativa Getresponse vs Mailchimp\",\"datePublished\":\"2019-12-18T06:28:28+00:00\",\"dateModified\":\"2020-09-07T11:28:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp\"},\"wordCount\":858,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/mailchimp-getresponse-comparativa.jpg\",\"articleSection\":[\"Marketing online\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp\",\"name\":\"Comparativa Getresponse vs Mailchimp | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/mailchimp-getresponse-comparativa.jpg\",\"datePublished\":\"2019-12-18T06:28:28+00:00\",\"dateModified\":\"2020-09-07T11:28:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"description\":\"Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/mailchimp-getresponse-comparativa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/mailchimp-getresponse-comparativa.jpg\",\"width\":852,\"height\":447},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/comparativa-getresponse-vs-mailchimp#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comparativa Getresponse vs Mailchimp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\",\"name\":\"Pablo Risue\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"caption\":\"Pablo Risue\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/www.4webs.es\"],\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comparativa Getresponse vs Mailchimp | 4webs.es","description":"Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp","og_locale":"es_ES","og_type":"article","og_title":"Comparativa Getresponse vs Mailchimp | 4webs.es","og_description":"Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo.","og_url":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2019-12-18T06:28:28+00:00","article_modified_time":"2020-09-07T11:28:25+00:00","og_image":[{"width":852,"height":447,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/mailchimp-getresponse-comparativa.jpg","type":"image\/jpeg"}],"author":"Pablo Risue\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Pablo Risue\u00f1o","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp"},"author":{"name":"Pablo Risue\u00f1o","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"headline":"Comparativa Getresponse vs Mailchimp","datePublished":"2019-12-18T06:28:28+00:00","dateModified":"2020-09-07T11:28:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp"},"wordCount":858,"commentCount":1,"image":{"@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/mailchimp-getresponse-comparativa.jpg","articleSection":["Marketing online"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp","url":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp","name":"Comparativa Getresponse vs Mailchimp | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/mailchimp-getresponse-comparativa.jpg","datePublished":"2019-12-18T06:28:28+00:00","dateModified":"2020-09-07T11:28:25+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"description":"Tanto GetResponse como MailChimp son las dos herramientas del mercado actual del email marketing m\u00e1s usadas en el mundo.","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/mailchimp-getresponse-comparativa.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2014\/12\/mailchimp-getresponse-comparativa.jpg","width":852,"height":447},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/comparativa-getresponse-vs-mailchimp#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"Comparativa Getresponse vs Mailchimp"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048","name":"Pablo Risue\u00f1o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","caption":"Pablo Risue\u00f1o"},"sameAs":["http:\/\/www.4webs.es"],"url":"https:\/\/www.4webs.es\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/4106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=4106"}],"version-history":[{"count":8,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/4106\/revisions"}],"predecessor-version":[{"id":11640,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/4106\/revisions\/11640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/4109"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=4106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=4106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=4106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}