{"id":11301,"date":"2019-07-02T18:47:36","date_gmt":"2019-07-02T17:47:36","guid":{"rendered":"https:\/\/www.4webs.es\/blog\/?p=11301"},"modified":"2019-07-02T18:47:36","modified_gmt":"2019-07-02T17:47:36","slug":"trucos-para-una-correcta-redaccion-de-textos-seo","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo","title":{"rendered":"Trucos para una correcta redacci\u00f3n de textos SEO"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p>Escribir para SEO se est\u00e1 convirtiendo en una tarea laboriosa, ya no basta con escribir todos los d\u00edas y meter mucha paja, ahora Google quiere contenido de calidad.<\/p>\n<p>El lema de <strong>\u00abEl contenido es el REY\u00bb<\/strong> est\u00e1 m\u00e1s vivo que nunca, si sigues estos consejos para redactar contenidos SEO te ser\u00e1 muy sencillo llegar a tus usuarios.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-flat ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de Contenidos<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\/#El_objetivo_de_un_buen_texto_SEO\" >El objetivo de un buen texto SEO<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\/#Claves_para_de_la_redaccion_SEO\" >Claves para de la redacci\u00f3n SEO:<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\/#%C2%BFHerramientas_para_hacer_busqueda_de_keywords\" >\u00bfHerramientas para hacer b\u00fasqueda de keywords?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\/#Estructura_del_contenido\" >Estructura del contenido<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\/#No_olvidarnos_de_la_Semantica\" >No olvidarnos de la Sem\u00e1ntica<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"El_objetivo_de_un_buen_texto_SEO\"><\/span>El objetivo de un buen texto SEO<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sobre todo buscamos que un <strong>buen texto SEO posicione y convierta al m\u00e1ximo n\u00famero de usuarios posibles<\/strong>. Usar textos que solo trabajen al 100% las keywords hoy en d\u00eda no vale de nada.<\/p>\n<p>Olvidaros de rellenar los art\u00edculos , de eliminar proposiciones y de repetir palabras claves, etc. Esto es <a href=\"https:\/\/www.4webs.es\/blog\/malas-practicas-seo-keyword-stuffing\">keyword stuffing<\/a> y ya no funciona para posicionar p\u00e1ginas.<\/p>\n<p>Olv\u00eddate de escribir para SEO y c\u00e9ntrate en estos tres puntos:<\/p>\n<ul>\n<li>El usuario debe poder leerlo facilmente<\/li>\n<li>Google o el buscador debe poder indexarlo, rastrearlo y rankearlo.<\/li>\n<li>Que convierta al m\u00e1ximo n\u00famero de usuarios posibles.<\/li>\n<\/ul>\n<p>Si hablamos de redacci\u00f3n de contenidos para productos, olvidaros de redacciones compradas sin un objetivo o sin un gui\u00f3n, habla de tu producto, explica las ventajas de tu producto.<\/p>\n<p>Para <a href=\"https:\/\/www.4webs.es\/marketing-contenidos\"><strong>redactar un texto de calidad que convierta<\/strong><\/a> vamos a tener que invertir tiempo en <strong>documentarnos<\/strong>, <strong>conseguir fuentes de calidad<\/strong> y redactar un contenido que tenga un hilo conductor, por lo tanto es imposible que alguien te redacte un texto de calidad por 10\u20ac, eso no existe.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Claves_para_de_la_redaccion_SEO\"><\/span>Claves para de la redacci\u00f3n SEO:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>Escribir para SEO no es una tarea sencilla<\/strong>, sobre todo porque tenemos que escribir de forma que al usuario le guste y el buscador, lo indexe y coloque en los primeros puestos de las SERPS.<\/p>\n<ul>\n<li>Saber al p\u00fablico al que nos dirigimos.<\/li>\n<li>Hacer el estudio de keywords en base a esa intenci\u00f3n de b\u00fasqueda.<\/li>\n<li>Escribir con naturalidad.<\/li>\n<li>No meter relleno.<\/li>\n<li>Deja para el final la parte de optimizaci\u00f3n de contenido o keywords.<\/li>\n<li>Trabajar la sem\u00e1ntica, es decir, no trabajar solo 1 keyword.<\/li>\n<li>Usar t\u00e9cnicas de redacci\u00f3n de textos correctas.<\/li>\n<\/ul>\n<p>Una vez que hemos decidido de que vamos a escribir, si por ejemplo, va a ser un art\u00edculo de un blog, una ficha de un producto, o una categor\u00eda, llega el momento de elegir aquellas palabras clave que son m\u00e1s interesantes, bien sea por volumen de b\u00fasqueda, por relevancia, o , por la intenci\u00f3n de b\u00fasqueda que queramos&#8230;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFHerramientas_para_hacer_busqueda_de_keywords\"><\/span>\u00bfHerramientas para hacer b\u00fasqueda de keywords?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Lo primero que debes realizar es saber que palabras clave usar, cual es la intenci\u00f3n de b\u00fasqueda y sobre todo, <strong>elegir un buen t\u00edtulo SEO que tenga suficiente volumen de b\u00fasqueda<\/strong>, para ello os recomendamos una serie de herramientas de b\u00fasqueda de palabras clave, el famoso Keyword Research que tan de moda est\u00e1:<\/p>\n<ul>\n<li>Google Suggest<\/li>\n<li>Keywordtool.io, junto son Semrush otra de mis favoritas para hacer un keyword research.<\/li>\n<li>Answer the public , es gratuita ,tambi\u00e9n muy buena descubrir contenidos para blogs.<\/li>\n<li>Seolyze, nos permite saber que contenidos usa la competencia y en que fallamos nosotros.<\/li>\n<li><a href=\"https:\/\/www.semrush.com\/sem\/?ref=2017035779&amp;refer_source=blog&amp;utm_source=berush&amp;utm_medium=promo&amp;utm_campaign=link\">Semrush con acceso gratis durante una semana<\/a> para que lo pod\u00e1is probar.<\/li>\n<li>Auto completador de Google.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Estructura_del_contenido\"><\/span>Estructura del contenido<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La estructura es otro de los puntos m\u00e1s importantes que deb\u00e9is tener en cuenta a la hora de redactar un texto, la estructura debe ser muy visual de cara a los usuarios, que tenga un orden, el usuario debe querer leer el contenido hasta el final desde que se comienza a leer.<\/p>\n<p><strong>No tiene sentido ponerse a poner palabras clave<\/strong> como un loco, esa t\u00e9cnica ya no funciona, c\u00e9ntrate en que el contenido sea legible para el usuario, y no para el buscador.<\/p>\n<p>Una <strong>buena forma de estructurarlo ser\u00eda con lo que en periodismo se conoce como la pir\u00e1mide invertida<\/strong>, lo m\u00e1s importante siempre debe estar arriba.<\/p>\n<figure id=\"attachment_11305\" aria-describedby=\"caption-attachment-11305\" style=\"width: 836px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11305\" src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/Tecnica-de-la-piramide-invertoda.jpg\" alt=\"Textos con la t\u00e9cnica pir\u00e1mide invertida\" width=\"836\" height=\"548\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/Tecnica-de-la-piramide-invertoda.jpg 836w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/Tecnica-de-la-piramide-invertoda-300x197.jpg 300w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/Tecnica-de-la-piramide-invertoda-641x420.jpg 641w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-11305\" class=\"wp-caption-text\">Textos con la t\u00e9cnica pir\u00e1mide invertida<\/figcaption><\/figure>\n<p>El funcionamiento de la pir\u00e1mide invertida es sencillo, te explicamos cada punto para que sepas como usarla:<\/p>\n<ul>\n<li>Titulo, el punto m\u00e1s importante, solo puede existir uno por p\u00e1gina.<\/li>\n<li>Primer p\u00e1rrafo, introducci\u00f3n al lector, no est\u00e1 de m\u00e1s usar alguna llamada a la acci\u00f3n.<\/li>\n<li>Desarrollo, podemos realizar llamadas a la acci\u00f3n en la parte de argumentaci\u00f3n y usar todas las keywords posibles, as\u00ed como sus sin\u00f3nimos, aqu\u00ed es donde podemos meter la chicha.<\/li>\n<li>Detalles, caracter\u00edsticas t\u00e9cnicas, opiniones, datos de menor valor.<\/li>\n<li>Fin, finalizaci\u00f3n, llamadas a la acci\u00f3n.<\/li>\n<\/ul>\n<p>En el primer p\u00e1rrafo deber\u00edamos marcar negritas aquellas palabras clave importantes, es la entrada, y sobre todo, trabajar la sem\u00e1ntica de la que voy a hablar en el contenido, en la parte de desarrollo.<\/p>\n<p>Es importante que los p\u00e1rrafos sean escuetos, entre 3 y 5 l\u00edneas deber\u00eda ser suficiente, no met\u00e1is relleno por favor..<\/p>\n<h3><span class=\"ez-toc-section\" id=\"No_olvidarnos_de_la_Semantica\"><\/span>No olvidarnos de la Sem\u00e1ntica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es la gran diferencia a d\u00eda de hoy entre los diferentes contenidos, y en los que te puedes diferenciar de tu competencia, pero sobre todo los que permitir\u00e1n que aparezcas en mejores posiciones.<\/p>\n<p>Hasta hace poco se posicionaba por palabras clave, <strong>hoy en d\u00eda se posiciona por intenci\u00f3n de b\u00fasqueda<\/strong>, eso quiere decir que posicionamos por un conjunto de palabras que determinan la intenci\u00f3n del usuario, un texto no es igual para un usuario que va a comprar, que para un usuario que va a buscar informaci\u00f3n.<\/p>\n<p>Por norma general cuando vendemos un producto, la primera fase del usuario es informarse, son <strong>contenidos informacionales<\/strong>, y cuando el cliente ya quiere comprar busca webs con <strong>informaci\u00f3n transaccional, de venta<\/strong>. As\u00ed es como trabaja Google ahora. Hablaremos m\u00e1s de este tema.<\/p>\n<p>Espero que os haya servido de ayuda, si necesit\u00e1is ayuda con vuestro proyecto, estamos aqu\u00ed para ayudaros!<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.<\/p>\n","protected":false},"author":1,"featured_media":11309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[164],"tags":[],"class_list":{"0":"post-11301","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seo"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trucos para una correcta redacci\u00f3n de textos SEO | 4webs.es<\/title>\n<meta name=\"description\" content=\"Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trucos para una correcta redacci\u00f3n de textos SEO | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-02T17:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/redactar-textos-seo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Risue\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Risue\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo\"},\"author\":{\"name\":\"Pablo Risue\u00f1o\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"headline\":\"Trucos para una correcta redacci\u00f3n de textos SEO\",\"datePublished\":\"2019-07-02T17:47:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo\"},\"wordCount\":996,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/redactar-textos-seo.jpg\",\"articleSection\":[\"Seo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo\",\"name\":\"Trucos para una correcta redacci\u00f3n de textos SEO | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/redactar-textos-seo.jpg\",\"datePublished\":\"2019-07-02T17:47:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"description\":\"Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/redactar-textos-seo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/redactar-textos-seo.jpg\",\"width\":840,\"height\":440,\"caption\":\"redactar-textos-seo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/trucos-para-una-correcta-redaccion-de-textos-seo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trucos para una correcta redacci\u00f3n de textos SEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\",\"name\":\"Pablo Risue\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"caption\":\"Pablo Risue\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/www.4webs.es\"],\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trucos para una correcta redacci\u00f3n de textos SEO | 4webs.es","description":"Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo","og_locale":"es_ES","og_type":"article","og_title":"Trucos para una correcta redacci\u00f3n de textos SEO | 4webs.es","og_description":"Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.","og_url":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2019-07-02T17:47:36+00:00","og_image":[{"width":840,"height":440,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/redactar-textos-seo.jpg","type":"image\/jpeg"}],"author":"Pablo Risue\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Pablo Risue\u00f1o","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo"},"author":{"name":"Pablo Risue\u00f1o","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"headline":"Trucos para una correcta redacci\u00f3n de textos SEO","datePublished":"2019-07-02T17:47:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo"},"wordCount":996,"commentCount":1,"image":{"@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/redactar-textos-seo.jpg","articleSection":["Seo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo","url":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo","name":"Trucos para una correcta redacci\u00f3n de textos SEO | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/redactar-textos-seo.jpg","datePublished":"2019-07-02T17:47:36+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"description":"Ya no basta con escribir art\u00edculos de forma peri\u00f3dica, ahora tenemos que redactar textos SEO que posicionen, te contamos algunas de las claves impresincidibles para ayudarte a salir en las primeras posiciones de los buscadores.","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/redactar-textos-seo.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2019\/07\/redactar-textos-seo.jpg","width":840,"height":440,"caption":"redactar-textos-seo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/trucos-para-una-correcta-redaccion-de-textos-seo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"Trucos para una correcta redacci\u00f3n de textos SEO"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048","name":"Pablo Risue\u00f1o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","caption":"Pablo Risue\u00f1o"},"sameAs":["http:\/\/www.4webs.es"],"url":"https:\/\/www.4webs.es\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/11301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=11301"}],"version-history":[{"count":18,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/11301\/revisions"}],"predecessor-version":[{"id":11344,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/11301\/revisions\/11344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/11309"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=11301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=11301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=11301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}