{"id":1076,"date":"2011-01-19T22:21:18","date_gmt":"2011-01-19T20:21:18","guid":{"rendered":"http:\/\/www.4webs.es\/blog\/?p=1076"},"modified":"2018-08-21T12:00:47","modified_gmt":"2018-08-21T11:00:47","slug":"modulo-prestashop-solicitar-informacion-en-ficha-producto","status":"publish","type":"post","link":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto","title":{"rendered":"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto"},"content":{"rendered":"<div class=\"row\"><div class=\"col-md-11 content-article\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1077\"  src=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg\" alt=\"\" width=\"551\" height=\"248\" srcset=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg 551w, https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop-300x135.jpg 300w\" sizes=\"auto, (max-width: 551px) 85vw, 551px\" \/><\/p>\n<p>El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar m\u00e1s informaci\u00f3n. Como siempre este tipo de m\u00f3dulo facilitan el uso a los clientes y por supuesto mejorar\u00e1 la usabilidad de nuestra <a  href=\"https:\/\/www.4webs.es\/tiendas-virtuales.php\">tienda online<\/a>.<\/p>\n<p>El backend de este m\u00f3dulo es bastante completo incluye una personalizaci\u00f3n completa del mismo:<\/p>\n<ul>\n<li>Captcha.<\/li>\n<li>Ubicaci\u00f3n del formulario dentro de la tienda.<\/li>\n<li>Imagen de fondo en el formulario.<\/li>\n<li>Transparencia de los textos<\/li>\n<li>L\u00edneas, bordes, colores, tipograf\u00edas.<\/li>\n<\/ul>\n<p>Vamos que podr\u00e9is controlar hasta el \u00faltima detalle con poco clicks y lo mejor de todo es que est\u00e1 realizado en Ajax.<\/p>\n<p><a href=\"http:\/\/www.prestashop.com\/forums\/viewthread\/81689\/third_party_modules\/module_askmoreinfo_allows_visitors_to_request_more_information_on_products_captcha\">Descarga del m\u00f3dulo<\/a><\/p>\n<p>Y pr\u00f3ximamente, integrar un gestor de im\u00e1genes para subir archivos en nuestro editor de textos que incluye la tienda online.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar m\u00e1s informaci\u00f3n. Como siempre este tipo de m\u00f3dulo facilitan el uso a los clientes y por supuesto mejorar\u00e1 la usabilidad de nuestra tienda online. El backend de este &hellip; <a href=\"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abM\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"class_list":{"0":"post-1076","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prestashop"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto | 4webs.es<\/title>\n<meta name=\"description\" content=\"El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto | 4webs.es\" \/>\n<meta property=\"og:description\" content=\"El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto\" \/>\n<meta property=\"og:site_name\" content=\"4webs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/4webs\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-19T20:21:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-21T11:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"248\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Risue\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@4webs\" \/>\n<meta name=\"twitter:site\" content=\"@4webs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Risue\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto\"},\"author\":{\"name\":\"Pablo Risue\u00f1o\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"headline\":\"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto\",\"datePublished\":\"2011-01-19T20:21:18+00:00\",\"dateModified\":\"2018-08-21T11:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto\"},\"wordCount\":154,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/formulario-contacto-ficha-prestashop.jpg\",\"articleSection\":[\"Prestashop\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto\",\"name\":\"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto | 4webs.es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/formulario-contacto-ficha-prestashop.jpg\",\"datePublished\":\"2011-01-19T20:21:18+00:00\",\"dateModified\":\"2018-08-21T11:00:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\"},\"description\":\"El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/formulario-contacto-ficha-prestashop.jpg\",\"contentUrl\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/formulario-contacto-ficha-prestashop.jpg\",\"width\":551,\"height\":248},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/modulo-prestashop-solicitar-informacion-en-ficha-producto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.4webs.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/\",\"name\":\"4webs\",\"description\":\"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/#\\\/schema\\\/person\\\/fc07e8cecb1e51ce56b131a1eb0b3048\",\"name\":\"Pablo Risue\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g\",\"caption\":\"Pablo Risue\u00f1o\"},\"sameAs\":[\"http:\\\/\\\/www.4webs.es\"],\"url\":\"https:\\\/\\\/www.4webs.es\\\/blog\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto | 4webs.es","description":"El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto","og_locale":"es_ES","og_type":"article","og_title":"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto | 4webs.es","og_description":"El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar","og_url":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto","og_site_name":"4webs","article_publisher":"https:\/\/www.facebook.com\/4webs","article_published_time":"2011-01-19T20:21:18+00:00","article_modified_time":"2018-08-21T11:00:47+00:00","og_image":[{"width":551,"height":248,"url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg","type":"image\/jpeg"}],"author":"Pablo Risue\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@4webs","twitter_site":"@4webs","twitter_misc":{"Escrito por":"Pablo Risue\u00f1o","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#article","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto"},"author":{"name":"Pablo Risue\u00f1o","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"headline":"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto","datePublished":"2011-01-19T20:21:18+00:00","dateModified":"2018-08-21T11:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto"},"wordCount":154,"commentCount":2,"image":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg","articleSection":["Prestashop"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto","url":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto","name":"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto | 4webs.es","isPartOf":{"@id":"https:\/\/www.4webs.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage"},"image":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage"},"thumbnailUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg","datePublished":"2011-01-19T20:21:18+00:00","dateModified":"2018-08-21T11:00:47+00:00","author":{"@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048"},"description":"El funcionamiento de este m\u00f3dulo es bastante sencillo aparece un link en cada ficha de cada producto donde se le da al usuario la posibilidad de solicitar","breadcrumb":{"@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#primaryimage","url":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg","contentUrl":"https:\/\/www.4webs.es\/blog\/wp-content\/uploads\/2011\/01\/formulario-contacto-ficha-prestashop.jpg","width":551,"height":248},{"@type":"BreadcrumbList","@id":"https:\/\/www.4webs.es\/blog\/modulo-prestashop-solicitar-informacion-en-ficha-producto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.4webs.es\/blog"},{"@type":"ListItem","position":2,"name":"M\u00f3dulo Prestashop solicitar informaci\u00f3n en ficha producto"}]},{"@type":"WebSite","@id":"https:\/\/www.4webs.es\/blog\/#website","url":"https:\/\/www.4webs.es\/blog\/","name":"4webs","description":"Desarrollo con Prestashop, gesti\u00f3n de proyectos ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.4webs.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.4webs.es\/blog\/#\/schema\/person\/fc07e8cecb1e51ce56b131a1eb0b3048","name":"Pablo Risue\u00f1o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6938f7637a533914c144759f6249310d5f8fdef83738a4641b2d151a17c19f97?s=96&d=mm&r=g","caption":"Pablo Risue\u00f1o"},"sameAs":["http:\/\/www.4webs.es"],"url":"https:\/\/www.4webs.es\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/comments?post=1076"}],"version-history":[{"count":2,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/1076\/revisions"}],"predecessor-version":[{"id":1134,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/posts\/1076\/revisions\/1134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media\/1077"}],"wp:attachment":[{"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/categories?post=1076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4webs.es\/blog\/wp-json\/wp\/v2\/tags?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}